{"id":3697,"date":"2014-11-30T23:40:27","date_gmt":"2014-11-30T23:40:27","guid":{"rendered":"http:\/\/barcelonaroom\/fr\/for-sale\/"},"modified":"2016-03-04T18:39:32","modified_gmt":"2016-03-04T17:39:32","slug":"a-vendre","status":"publish","type":"page","link":"https:\/\/barcelonaroom.com\/fr\/a-vendre\/","title":{"rendered":"\u00c0 VENDRE"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\">Bienvenue. <a href=\"https:\/\/barcelonaroom.com\/\"><span class=\"s2\">Barcelonaroom.com<\/span><\/a> vous aidera \u00e0 trouver votre nouvelle maison ou terrain ou immeuble . Nous offrons des conseils d&rsquo;expert afin de trouver votre prochaine propri\u00e9t\u00e9 .Vous trouverez une liste d\u2019offres en vente ci-dessous , n\u2019h\u00e9sitez pas \u00e0 nous contacter pour organiser des visites ou pour en savoir plus .<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bienvenue. Barcelonaroom.com vous aidera \u00e0 trouver votre nouvelle maison ou terrain ou immeuble . Nous offrons des conseils d&rsquo;expert afin de trouver votre prochaine propri\u00e9t\u00e9 .Vous trouverez une liste d\u2019offres en vente ci-dessous , n\u2019h\u00e9sitez pas \u00e0 nous contacter pour organiser des visites ou pour en savoir plus .<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":126,"comment_status":"open","ping_status":"closed","template":"page-accommodation-list.php","meta":{"footnotes":""},"class_list":["post-3697","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/barcelonaroom.com\/fr\/wp-json\/wp\/v2\/pages\/3697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/barcelonaroom.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/barcelonaroom.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/barcelonaroom.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/barcelonaroom.com\/fr\/wp-json\/wp\/v2\/comments?post=3697"}],"version-history":[{"count":0,"href":"https:\/\/barcelonaroom.com\/fr\/wp-json\/wp\/v2\/pages\/3697\/revisions"}],"wp:attachment":[{"href":"https:\/\/barcelonaroom.com\/fr\/wp-json\/wp\/v2\/media?parent=3697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}